{"id":11336,"date":"2019-07-14T16:14:23","date_gmt":"2019-07-14T14:14:23","guid":{"rendered":"http:\/\/www.oboa.de\/wordpress\/?p=11336"},"modified":"2020-02-22T09:39:12","modified_gmt":"2020-02-22T07:39:12","slug":"oboa-warm-up-party-tattoo-soli","status":"publish","type":"post","link":"https:\/\/www.oboa.de\/wordpress\/oboa-warm-up-party-tattoo-soli\/","title":{"rendered":"OBOA WARM UP PARTY &#038; TATTOO SOLI"},"content":{"rendered":"\n<p>Freitag, 26. Juli 2019 von 23:00 bis 08:00<\/p>\n\n\n\n<p>TATTOO SOLI FLOOR 18.00 &#8211; 00.00 UHR<br>ARTISTS: @smeemachts @b.ignorant @uschi.3000 and more soon<\/p>\n\n\n\n<p>Kulturhaus Kili<br>Wiesenweg 5-9, 10365 Berlin<\/p>\n\n\n\n<p>Mainfloor : (Breakbeat\/HappyBreaks\/JumpUp\/Jungle\/DnB)<\/p>\n\n\n\n<p>Trem (Return Of The Hardcore \/ Hkcrw)<br>Jim Bean (Return Of The Hardcore \/ Orbitalwaves)<br>Dirty Plates (Bass Powered Movement)<br>Hughda Jones (Ganz Gut DJ Team)<br>Schlottstepp (Oboa)<br>H\u00e4gen Daz (Oboa)<\/p>\n\n\n\n<p>Secondfloor:<br>Trash Chaos Dj Team &#8230; More Infos soon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Freitag, 26. Juli 2019 von 23:00 bis 08:00 TATTOO SOLI FLOOR 18.00 &#8211; 00.00 UHRARTISTS: @smeemachts @b.ignorant @uschi.3000 and more soon Kulturhaus KiliWiesenweg 5-9, 10365 [&#8230;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_jetpack_memberships_contains_paid_content":false},"categories":[1,47],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","pl","gb","es"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"pl":{"title":false,"content":false,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/posts\/11336"}],"collection":[{"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11336"}],"version-history":[{"count":1,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/posts\/11336\/revisions"}],"predecessor-version":[{"id":11337,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/posts\/11336\/revisions\/11337"}],"wp:attachment":[{"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oboa.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}